{"id":15683,"date":"2019-07-26T13:20:24","date_gmt":"2019-07-26T11:20:24","guid":{"rendered":"https:\/\/www.conforama.live\/blog\/?p=15683"},"modified":"2022-06-07T12:53:02","modified_gmt":"2022-06-07T10:53:02","slug":"salones-modernos-tendencias-que-estan-arrasando","status":"publish","type":"post","link":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/","title":{"rendered":"Salones modernos: las tendencias que van a arrasar"},"content":{"rendered":"<p>Si te apasionan los salones modernos, \u00a1este art\u00edculo est\u00e1 escrito para ti! Y no solo eso, <strong>Victor Ramos, Product Manager de Salones y Responsable de Tendencias en Conforama te cuenta en el siguiente v\u00eddeo todo lo que necesitas saber sobre lo que se va a llevar en salones<\/strong> durante la pr\u00f3xima temporada. \u00a1Dale al play!<\/p>\n<div class=\"\u201dvideo-responsive\u201d\" align=\"center\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Slncik6s3zA\" width=\"100%\" height=\"600\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<h2>Los elementos que no deben faltar en los salones modernos<\/h2>\n<p>Tienes que tener claro<strong> qu\u00e9 tipo de <a target=\"_blank\" href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-salon?utm_source=Blog&amp;utm_medium=salon&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\" title=\"Salones modernos en Conforama\">sal\u00f3n<\/a> es el m\u00e1s recomendable<\/strong> seg\u00fan algunos aspectos. \u00bfCu\u00e1nto espacio disponible tienes? \u00bfC\u00f3mo es su forma? \u00bfLa estancia es sim\u00e9trica? Las respuestas a estas preguntas te llevar\u00e1n a poder introducir m\u00e1s o menos elementos para completar la estancia.<\/p>\n<p>Puedes optar por <strong>un sal\u00f3n modular, es decir, puedes personalizar tu sal\u00f3n introduciendo tantas piezas como quieras<\/strong>. Si tienes espacio disponible suficiente, puedes empezar a\u00f1adiendo un mueble para la TV y despu\u00e9s completarlo con m\u00e1s m\u00f3dulos, vitrinas, aparador,\u2026<\/p>\n<figure id=\"attachment_15688\" aria-describedby=\"caption-attachment-15688\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15688 size-full\" title=\"Sal\u00f3n DIMARO, uno de los salones modernos que aporta personalizaci\u00f3n\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-DIMARO-uno-de-los-salones-modernos-que-aporta-personalizaci\u00f3n-del-espacio.jpg\" alt=\"salones modernos\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-DIMARO-uno-de-los-salones-modernos-que-aporta-personalizaci\u00f3n-del-espacio.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-DIMARO-uno-de-los-salones-modernos-que-aporta-personalizaci\u00f3n-del-espacio-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-DIMARO-uno-de-los-salones-modernos-que-aporta-personalizaci\u00f3n-del-espacio-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-DIMARO-uno-de-los-salones-modernos-que-aporta-personalizaci\u00f3n-del-espacio-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15688\" class=\"wp-caption-text\">Personaliza tu sal\u00f3n con un modular, como el DIMARO<\/figcaption><\/figure>\n<p style=\"text-align: center;\"><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:637,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;12&quot;:0}\"><\/span><\/p>\n<p>En cambio, <strong>si optas por un sal\u00f3n compacto tendr\u00e1s todo el mueble de tu sal\u00f3n en una sola pieza<\/strong>. Tambi\u00e9n tendr\u00e1s espacio para colocar tu TV y m\u00faltiples opciones que ofrecen un amplio espacio de almacenamiento.<\/p>\n<figure id=\"attachment_15690\" aria-describedby=\"caption-attachment-15690\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15690 size-full\" title=\"Sal\u00f3n VETTERA, sal\u00f3n compacto, con acabado en piedra y gris\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VETTERA-sal\u00f3n-compacto-con-acabado-en-piedra-y-gris.jpg\" alt=\"salones modernos\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VETTERA-sal\u00f3n-compacto-con-acabado-en-piedra-y-gris.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VETTERA-sal\u00f3n-compacto-con-acabado-en-piedra-y-gris-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VETTERA-sal\u00f3n-compacto-con-acabado-en-piedra-y-gris-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VETTERA-sal\u00f3n-compacto-con-acabado-en-piedra-y-gris-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15690\" class=\"wp-caption-text\">Sal\u00f3n VETTERA, sal\u00f3n compacto, con acabado en piedra y gris<\/figcaption><\/figure>\n<p>Independientemente de todo esto, en los salones modernos no puede faltar:<\/p>\n<ul>\n<li>Un mueble TV o compacto, pieza imprescindible en esta estancia.<\/li>\n<li>Una mesa de sal\u00f3n con sillas.<\/li>\n<li>Un <a href=\"https:\/\/www.conforama.live\/sofas\/sofas?utm_source=Blog&amp;utm_medium=Sofa&amp;utm_campaign=Inbound+Marketing\">sof\u00e1<\/a> con una mesa de centro<\/li>\n<li>Un aparador para dar el servicio a la mesa de sal\u00f3n, si hay suficiente espacio.<\/li>\n<\/ul>\n<h2>Los colores y materiales que marcar\u00e1n tendencia<\/h2>\n<p>La <strong>tendencia en acabados de los salones modernos<\/strong> para la pr\u00f3xima temporada viene marcada por los <strong>blancos mate<\/strong> combinados con distintos materiales: como el roble natural, roble gris\u00e1ceo o con los acabados cemento y piedra.<\/p>\n<h3>Sal\u00f3n TEIMLO: blanco mate + roble<\/h3>\n<p>El sal\u00f3n TEIMLO es una de las novedades que re\u00fane todas estas tendencias, es un sal\u00f3n ideal que adem\u00e1s, aporta mucha luz y tiene un dise\u00f1o muy limpio.<\/p>\n<figure id=\"attachment_15692\" aria-describedby=\"caption-attachment-15692\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15692 size-full\" title=\"Sal\u00f3n TEIMLO, tendencias en sus colores y materiales: blanco mate combinado con roble\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-TEIMLO-tendencias-en-sus-colores-y-materiales.jpg\" alt=\"salones modernos\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-TEIMLO-tendencias-en-sus-colores-y-materiales.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-TEIMLO-tendencias-en-sus-colores-y-materiales-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-TEIMLO-tendencias-en-sus-colores-y-materiales-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-TEIMLO-tendencias-en-sus-colores-y-materiales-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15692\" class=\"wp-caption-text\">Sal\u00f3n TEIMLO, tendencias en sus colores y materiales: blanco mate combinado con roble<\/figcaption><\/figure>\n<h3>Sal\u00f3n COOPER: acabado \u00f3xido<\/h3>\n<p>Una de las tendencias que est\u00e1n cogiendo peso son los <b>acabados \u00f3xido\u00a0combinados<\/b> con diferentes robles. Este acabado solo se utiliza para detalles y alg\u00fan que otro frontal, ya que\u00a0los muebles modernos en este acabado ser\u00edan demasiado cargante para nuestra vista.<\/p>\n<figure id=\"attachment_15694\" aria-describedby=\"caption-attachment-15694\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15694 size-full\" title=\"El sal\u00f3n COOPER tiene un toque \u00f3xido en sus traseras\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-COOPER-acabados-en-\u00f3xido.jpg\" alt=\"salones modernos\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-COOPER-acabados-en-\u00f3xido.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-COOPER-acabados-en-\u00f3xido-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-COOPER-acabados-en-\u00f3xido-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-COOPER-acabados-en-\u00f3xido-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15694\" class=\"wp-caption-text\">El sal\u00f3n COOPER tiene un toque \u00f3xido en sus traseras<\/figcaption><\/figure>\n<p>Tambi\u00e9n puedes encontrar un efecto <strong>\u00f3xido con tonalidad gris\u00e1cea, es un efecto m\u00e1s sutil<\/strong> y menos marcado que el rojizo.<\/p>\n<figure id=\"attachment_15696\" aria-describedby=\"caption-attachment-15696\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15696 size-full\" title=\"El sal\u00f3n NUEVA YORK est\u00e1 hecho con un material con efecto \u00f3xido gris\u00e1ceo\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/El-sal\u00f3n-NUEVA-YORK-est\u00e1-hecho-con-un-material-con-efecto-\u00f3xido-gris\u00e1ceo.jpg\" alt=\"salones modernos\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/El-sal\u00f3n-NUEVA-YORK-est\u00e1-hecho-con-un-material-con-efecto-\u00f3xido-gris\u00e1ceo.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/El-sal\u00f3n-NUEVA-YORK-est\u00e1-hecho-con-un-material-con-efecto-\u00f3xido-gris\u00e1ceo-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/El-sal\u00f3n-NUEVA-YORK-est\u00e1-hecho-con-un-material-con-efecto-\u00f3xido-gris\u00e1ceo-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/El-sal\u00f3n-NUEVA-YORK-est\u00e1-hecho-con-un-material-con-efecto-\u00f3xido-gris\u00e1ceo-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15696\" class=\"wp-caption-text\">El sal\u00f3n NUEVA YORK est\u00e1 hecho con un material con efecto \u00f3xido gris\u00e1ceo<\/figcaption><\/figure>\n<h2>Las sillas de sal\u00f3n: una pieza clave<\/h2>\n<h3>Sillas que nunca pasan de moda<\/h3>\n<p>Una <a target=\"_blank\" href=\"https:\/\/www.conforama.live\/muebles\/sillas\/sillas-de-comedor?utm_source=Blog&amp;utm_medium=sillas&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\">silla<\/a> que nunca pasar\u00e1 de moda y que se puede incorporar a la mayor\u00eda de estilos de salones es la silla GANT, fabricada en patas de madera y tapizada en polipiel. Es un modelo <strong>muy pr\u00e1ctico a la hora de limpiar<\/strong> ya que cualquier posible mancha puede salir con un trapo h\u00famedo.<\/p>\n<figure id=\"attachment_15698\" aria-describedby=\"caption-attachment-15698\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15698\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-GANT-tapizada-en-polipiel.jpg\" alt=\"salones modernos\" width=\"600\" height=\"900\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-GANT-tapizada-en-polipiel.jpg 600w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-GANT-tapizada-en-polipiel-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-GANT-tapizada-en-polipiel-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-GANT-tapizada-en-polipiel-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-GANT-tapizada-en-polipiel-160x240.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-15698\" class=\"wp-caption-text\">La silla tapizada en polipiel de color blanco que nunca pasar\u00e1 de moda se llama GANT<\/figcaption><\/figure>\n<p>Otra de las sillas que nunca pasar\u00e1 de moda es la silla SADE, tapizada en chenilla natural que ofrecer\u00e1 m\u00e1s calidez al comedor y es apta para todo tipo de salones.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<figure id=\"attachment_15700\" aria-describedby=\"caption-attachment-15700\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15700\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-SADE-un-cl\u00e1sico-que-nunca-pasar\u00e1-de-moda.jpg\" alt=\"salones modernos\" width=\"600\" height=\"900\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-SADE-un-cl\u00e1sico-que-nunca-pasar\u00e1-de-moda.jpg 400w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-SADE-un-cl\u00e1sico-que-nunca-pasar\u00e1-de-moda-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-SADE-un-cl\u00e1sico-que-nunca-pasar\u00e1-de-moda-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-SADE-un-cl\u00e1sico-que-nunca-pasar\u00e1-de-moda-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-SADE-un-cl\u00e1sico-que-nunca-pasar\u00e1-de-moda-160x240.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-15700\" class=\"wp-caption-text\">Silla SADE, un cl\u00e1sico que nunca pasar\u00e1 de moda<\/figcaption><\/figure>\n<h3>Las sillas m\u00e1s innovadoras<\/h3>\n<p>Una de las sillas m\u00e1s innovadoras en nuestra colecci\u00f3n es la <strong>silla DOVER<\/strong> debido a su forma de pie de tipo cantil\u00e9ver y el tejido en acabado <em>vintage<\/em>. Es una silla perfecta para salones modernos.<\/p>\n<figure id=\"attachment_15702\" aria-describedby=\"caption-attachment-15702\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15702 size-full\" title=\"Silla DOVER, la silla m\u00e1s innovadora con efecto vintage\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-DOVER-la-silla-m\u00e1s-innovadora-con-efecto-vintage.jpg\" alt=\"salones modernos\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-DOVER-la-silla-m\u00e1s-innovadora-con-efecto-vintage.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-DOVER-la-silla-m\u00e1s-innovadora-con-efecto-vintage-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-DOVER-la-silla-m\u00e1s-innovadora-con-efecto-vintage-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-DOVER-la-silla-m\u00e1s-innovadora-con-efecto-vintage-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15702\" class=\"wp-caption-text\">Silla DOVER, la silla m\u00e1s innovadora con efecto vintage<\/figcaption><\/figure>\n<p>Por otro lado tenemos la <strong>silla FASHION<\/strong> de aire moderno retro con estructura de patas met\u00e1licas negro y tapizado en chenilla con colores tan de moda como el mostaza.<\/p>\n<figure id=\"attachment_15704\" aria-describedby=\"caption-attachment-15704\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15704 size-full\" title=\"La silla FASHION, se puede encontrar en colores tan atrevidos como el mostaza o en gris\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-FASHION.jpg\" alt=\"salones modernos\" width=\"600\" height=\"900\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-FASHION.jpg 400w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-FASHION-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-FASHION-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-FASHION-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-FASHION-160x240.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-15704\" class=\"wp-caption-text\">La <a href=\"https:\/\/www.conforama.live\/muebles\/sillas\/sillas-de-comedor?utm_source=Blog&amp;utm_medium=Sillas+de+comedor&amp;utm_campaign=Inbound+Marketing\">silla<\/a> FASHION, se puede encontrar en colores tan atrevidos como el mostaza o en gris<\/figcaption><\/figure>\n<p>Y para acabar la <strong>silla VELVET<\/strong> tapizada en terciopelo y con estilo retro, la puedes encontrar en 4 colores: verde, azul, rojo y gris.<\/p>\n<figure id=\"attachment_15706\" aria-describedby=\"caption-attachment-15706\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15706 size-full\" title=\"Silla VELVET, de aire retro y tapizada en terciopelo\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-VELVET-de-aire-retro-y-tapizada-en-terciopelo.jpg\" alt=\"Silla VELVET, de aire retro y tapizada en terciopelo\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-VELVET-de-aire-retro-y-tapizada-en-terciopelo.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-VELVET-de-aire-retro-y-tapizada-en-terciopelo-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-VELVET-de-aire-retro-y-tapizada-en-terciopelo-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Silla-VELVET-de-aire-retro-y-tapizada-en-terciopelo-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15706\" class=\"wp-caption-text\">Silla VELVET, de aire retro y tapizada en terciopelo<\/figcaption><\/figure>\n<h2>El sal\u00f3n m\u00e1s vendido en Conforama: inspiraci\u00f3n para salones modernos<\/h2>\n<p>El n\u00famero 1 es el <strong>sal\u00f3n VERONA<\/strong>, el motivo por el que se ha convertido en el m\u00e1s vendido es debido a su dise\u00f1o tradicional que <strong>encaja en todas las edades, estilos y gustos<\/strong>.<\/p>\n<p style=\"text-align: center;\"><\/p>\n<p>Adem\u00e1s, al ser modular puede adaptarse a cualquier tipo de espacio y esto te permite montar un sal\u00f3n con los elementos que te hagan falta en funci\u00f3n de las medidas del espacio disponible.<\/p>\n<p>La <a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-salon\/mesas-de-salon\/mesas-de-comedor?utm_source=Blog&amp;utm_medium=mesa+comedor&amp;utm_campaign=Inbound+Marketing\">mesa<\/a>, que es una de las piezas tambi\u00e9n m\u00e1s vendidas, es extensible y su base hace que tenga <strong>una estructura complemente diferente a las mesas de cuatro patas<\/strong> que estamos acostumbrados a ver.<\/p>\n<figure id=\"attachment_15708\" aria-describedby=\"caption-attachment-15708\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15708 size-full\" title=\"Sal\u00f3n VERONA\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VERONA-CONFORAMA.jpg\" alt=\"Sal\u00f3n VERONA CONFORAMA\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VERONA-CONFORAMA.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VERONA-CONFORAMA-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VERONA-CONFORAMA-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/Sal\u00f3n-VERONA-CONFORAMA-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-15708\" class=\"wp-caption-text\">Sal\u00f3n VERONA, el m\u00e1s deseado<\/figcaption><\/figure>\n<p style=\"text-align: left;\">\u00bfQu\u00e9 te han parecido las propuestas de Victor Ramos en <strong>salones modernos<\/strong> para la pr\u00f3xima temporada?<\/p>\n<p style=\"text-align: center;\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si te apasionan los salones modernos, \u00a1este art\u00edculo est\u00e1 escrito para ti! Y no solo<\/p>\n","protected":false},"author":10,"featured_media":15711,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1400,1789],"tags":[1555],"class_list":["post-15683","post","type-post","status-publish","format-standard","has-post-thumbnail","placeholder-for-hentry","category-decoracion-estancias","category-decoracion-salon","tag-salon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salones modernos: las tendencias que van a arrasar<\/title>\n<meta name=\"description\" content=\"Victor Ramos, Product Manager en salones y Responsable de Tendencias en Conforama, nos desvela los secretos de los salones modernos de la pr\u00f3xima temporada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salones modernos: las tendencias que van a arrasar\" \/>\n<meta property=\"og:description\" content=\"Victor Ramos, Product Manager en salones y Responsable de Tendencias en Conforama, nos desvela los secretos de los salones modernos de la pr\u00f3xima temporada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\" \/>\n<meta property=\"og:site_name\" content=\"Conforama\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-26T11:20:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-07T10:53:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Conforama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conforama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\"},\"author\":{\"name\":\"Conforama\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\"},\"headline\":\"Salones modernos: las tendencias que van a arrasar\",\"datePublished\":\"2019-07-26T11:20:24+00:00\",\"dateModified\":\"2022-06-07T10:53:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\"},\"wordCount\":976,\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg\",\"keywords\":[\"sal\u00f3n\"],\"articleSection\":[\"Decoraci\u00f3n\",\"Decoraci\u00f3n de sal\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\",\"url\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\",\"name\":\"Salones modernos: las tendencias que van a arrasar\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg\",\"datePublished\":\"2019-07-26T11:20:24+00:00\",\"dateModified\":\"2022-06-07T10:53:02+00:00\",\"description\":\"Victor Ramos, Product Manager en salones y Responsable de Tendencias en Conforama, nos desvela los secretos de los salones modernos de la pr\u00f3xima temporada.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage\",\"url\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg\",\"contentUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg\",\"width\":762,\"height\":250,\"caption\":\"salones modernos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.conforama.live\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decoraci\u00f3n\",\"item\":\"https:\/\/www.conforama.live\/blog\/decoracion-estancias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salones modernos: las tendencias que van a arrasar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"name\":\"Blog Conforama\",\"description\":\"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos\",\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conforama.live\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\",\"name\":\"Conforama\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"contentUrl\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"width\":265,\"height\":72,\"caption\":\"Conforama\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\",\"name\":\"Conforama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"caption\":\"Conforama\"},\"url\":\"https:\/\/www.conforama.live\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salones modernos: las tendencias que van a arrasar","description":"Victor Ramos, Product Manager en salones y Responsable de Tendencias en Conforama, nos desvela los secretos de los salones modernos de la pr\u00f3xima temporada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/","og_locale":"es_ES","og_type":"article","og_title":"Salones modernos: las tendencias que van a arrasar","og_description":"Victor Ramos, Product Manager en salones y Responsable de Tendencias en Conforama, nos desvela los secretos de los salones modernos de la pr\u00f3xima temporada.","og_url":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/","og_site_name":"Conforama","article_published_time":"2019-07-26T11:20:24+00:00","article_modified_time":"2022-06-07T10:53:02+00:00","og_image":[{"width":762,"height":250,"url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg","type":"image\/jpeg"}],"author":"Conforama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Conforama","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#article","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/"},"author":{"name":"Conforama","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e"},"headline":"Salones modernos: las tendencias que van a arrasar","datePublished":"2019-07-26T11:20:24+00:00","dateModified":"2022-06-07T10:53:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/"},"wordCount":976,"publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg","keywords":["sal\u00f3n"],"articleSection":["Decoraci\u00f3n","Decoraci\u00f3n de sal\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/","url":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/","name":"Salones modernos: las tendencias que van a arrasar","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg","datePublished":"2019-07-26T11:20:24+00:00","dateModified":"2022-06-07T10:53:02+00:00","description":"Victor Ramos, Product Manager en salones y Responsable de Tendencias en Conforama, nos desvela los secretos de los salones modernos de la pr\u00f3xima temporada.","breadcrumb":{"@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#primaryimage","url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg","contentUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/07\/salones-modernos.jpg","width":762,"height":250,"caption":"salones modernos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conforama.live\/blog\/"},{"@type":"ListItem","position":2,"name":"Decoraci\u00f3n","item":"https:\/\/www.conforama.live\/blog\/decoracion-estancias\/"},{"@type":"ListItem","position":3,"name":"Salones modernos: las tendencias que van a arrasar"}]},{"@type":"WebSite","@id":"https:\/\/www.conforama.live\/blog\/#website","url":"https:\/\/www.conforama.live\/blog\/","name":"Blog Conforama","description":"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos","publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conforama.live\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.conforama.live\/blog\/#organization","name":"Conforama","url":"https:\/\/www.conforama.live\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","contentUrl":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","width":265,"height":72,"caption":"Conforama"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e","name":"Conforama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","caption":"Conforama"},"url":"https:\/\/www.conforama.live\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/15683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/comments?post=15683"}],"version-history":[{"count":16,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/15683\/revisions"}],"predecessor-version":[{"id":34190,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/15683\/revisions\/34190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media\/15711"}],"wp:attachment":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media?parent=15683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/categories?post=15683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/tags?post=15683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}