{"id":16883,"date":"2019-10-17T20:17:53","date_gmt":"2019-10-17T18:17:53","guid":{"rendered":"https:\/\/www.conforama.live\/blog\/?p=16883"},"modified":"2022-10-24T12:55:14","modified_gmt":"2022-10-24T10:55:14","slug":"6-tendencias-para-el-salon","status":"publish","type":"post","link":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/","title":{"rendered":"Tendencias para el sal\u00f3n: 6 claves para este 2020"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Es uno de los lugares de la casa donde m\u00e1s tiempo se pasa al d\u00eda, sobre todo durante los fines de semana. <\/span>Y, en esencia, es tambi\u00e9n el centro de una vivienda, ese lugar en el que todo el mundo desea estar porque es c\u00f3modo, pr\u00e1ctico y muy atractivo.<span style=\"font-weight: 400;\"> Hablamos del sal\u00f3n, un espacio \u00fanico; por eso, no te puedes perder estas&nbsp;<strong>tendencias para el sal\u00f3n<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es el mejor lugar para pasar tiempo disfrutando con los tuyos de una pel\u00edcula, comiendo o cenando con un grupo de amigos, o simplemente leyendo tu libro favorito en el sal\u00f3n. <\/span><b>Te presentamos las 6 tendencias para el sal\u00f3n <\/b>que debes conocer cuanto antes si quieres renovarlos o, simplemente, realizar algunos cambios concretos en \u00e9l.<b> <\/b><span style=\"font-weight: 400;\">Rel\u00e1jate y toma nota de las ideas que m\u00e1s te interesen.<\/span><\/p>\n<figure id=\"attachment_16898\" aria-describedby=\"caption-attachment-16898\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/sofas\/sofas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16898\" title=\"Sof\u00e1 de terciopelo VEGA con pouf a juego\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-1.jpg\" alt=\"tendencias salon \" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-1.jpg 1071w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-1-300x200.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-1-768x512.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-1-1024x683.jpg 1024w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-1-320x213.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-16898\" class=\"wp-caption-text\"><a href=\"https:\/\/www.conforama.live\/sofas\/sofas?utm_source=Blog&amp;utm_medium=Sofa&amp;utm_campaign=Inbound+Marketing\">Sof\u00e1<\/a> de terciopelo VEGA con pouf a juego<\/figcaption><\/figure>\n<h2>1. Exotic Chic: viajar sin salir de casa<\/h2>\n<p><span style=\"font-weight: 400;\">La&nbsp;<\/span><span style=\"font-weight: 400;\">madera, las cuerdas, el mimbre o la alfarer\u00eda jugar\u00e1n un papel fundamental en la estancia, tanto con un papel decorativo como con un papel funcional; de las m\u00e1scaras tribales puedes pasar a las cestas de arpillera, que adem\u00e1s son muy \u00fatiles para organizar. <\/span><b>Atr\u00e9vete con alfombras de lana bereber o con animal print y con papeles pintados con mapas. <\/b><span style=\"font-weight: 400;\">Tambi\u00e9n puedes restaurar una maleta antigua y emplearla como elemento decorativo, o incluso integrarla en una mesa baja. En cuanto a los colores, la base ser\u00e1 blanca y negra y los tonos naturales y c\u00e1lidos, con especial atenci\u00f3n a los terrosos.&nbsp;&nbsp;<\/span><\/p>\n<p style=\"text-align: center;\"><\/p>\n<p><span style=\"font-weight: 400;\">Viajar explorando nuevos pa\u00edses y entornos, en especial si es buscando el encuentro con la naturaleza, es una tendencia innata en el hombre desde tiempos inmemoriales. <\/span><b>Ese af\u00e1n por descubrir lugares nuevos y visitar culturas ajenas es el que se trasluce en una de las tendencias para el sal\u00f3n que han llegado con m\u00e1s intensidad.<\/b><span style=\"font-weight: 400;\"> \u00c1frica y Asia son las grandes protagonistas a la hora de inspirar este estilo, caracterizado por el \u00e9nfasis en los materiales artesanales y hechos a mano.&nbsp;<\/span><\/p>\n<figure id=\"attachment_16900\" aria-describedby=\"caption-attachment-16900\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-salon?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16900 size-full\" title=\"Sal\u00f3n VERONA con decoraci\u00f3n Exotic Chic\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-2.jpg\" alt=\"tendencias salon \" width=\"600\" height=\"900\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-2.jpg 600w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-2-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-2-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-2-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-2-160x240.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-16900\" class=\"wp-caption-text\">Sal\u00f3n VERONA con decoraci\u00f3n Exotic Chic<\/figcaption><\/figure>\n<h2><strong>2. Mantener a la vista la vajilla retro, una tendencia para sal\u00f3n en auge<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">La vajilla es una de las <\/span>10 piezas clave para convertir tu sal\u00f3n en una portada de revista<span style=\"font-weight: 400;\">. <\/span><b>Dejar visibles los elementos de menaje es una de las tendencias para sal\u00f3n que tienen m\u00e1s&nbsp; fuerza si sabemos c\u00f3mo colocarlos<\/b><span style=\"font-weight: 400;\">. Hay que tener en cuenta que su lugar \u2018natural\u2019 es la cocina, por eso hay que escoger bien los que podemos dejar en el sal\u00f3n y colocarlos con armon\u00eda. Los elementos grandes, como bandejas, o fuentes soperas, crean un interesante efecto visual. <\/span><b>Ten presente el poder evocador de la vajilla retro; por ejemplo una taza de chocolate puede evocar las tardes de la infancia en las que se degustaba junto a hermanos y amigos.<\/b><span style=\"font-weight: 400;\"> Rescata la loza o la porcelana familiar para redecorar el sal\u00f3n ense\u00f1ando, de paso, un pedazo de la historia familiar.<\/span><\/p>\n<figure id=\"attachment_16902\" aria-describedby=\"caption-attachment-16902\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-cocina?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16902 size-full\" title=\"Vajilla HAPPY de 18 piezas\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-3.jpg\" alt=\"tendencias salon \" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-3.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-3-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-3-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-3-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-16902\" class=\"wp-caption-text\">Vajilla HAPPY de 18 piezas<\/figcaption><\/figure>\n<h2><strong>3. Madera oscura: elegancia y sencillez<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Puede que no se hable de los tonos oscuros para la madera cuando se habla de <\/span><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/blog\/salones-modernos-tendencias-que-estan-arrasando\/\" rel=\"noopener\"><span style=\"font-weight: 400;\">salones modernos o de las tendencias que van a arrasar<\/span><\/a><span style=\"font-weight: 400;\">, pero eso es porque se trata de un cl\u00e1sico permanente. Los tonos marrones y de grises intensos, as\u00ed como los de nogal, aportan sobriedad y elegancia al tiempo que dan un aire de sencillez muy apreciado. Si utilizamos para combinarlos, colores en piedra y cemento, el resultado es m\u00e1s que satisfactorio.&nbsp;<\/span><\/p>\n<figure id=\"attachment_16905\" aria-describedby=\"caption-attachment-16905\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-salon?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16905 size-full\" title=\"Conjunto de sal\u00f3n de la serie DIMARO\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-4.jpg\" alt=\"tendencias salon \" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-4.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-4-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-4-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-4-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-16905\" class=\"wp-caption-text\">Conjunto de sal\u00f3n de la serie DIMARO<\/figcaption><\/figure>\n<h2><strong>4. Juega con las alfombras hasta que \u2018des con la tecla\u2019<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Hay tantas alfombras como estilos de decoraci\u00f3n y como propietarios. Por eso la mejor recomendaci\u00f3n que podemos hacer acerca de ellas es que busques y rebusques hasta que des con la que mejor se adapta a tu sal\u00f3n y, por supuesto, a tus gustos. <\/span><b>Aunque la oferta es inabarcable, las alfombras degradadas est\u00e1n ganando muchos adeptos y se combinan muy bien con paredes de colores claros y, por contraste, con muebles de tonos intensos.<\/b><span style=\"font-weight: 400;\"> Si eres de arriesgar un poco en el estilo de tu casa, puedes decantarte por colores azules, burdeos y mostazas. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">A la hora de planificar, recuerda el tipo de suelo con el que cuentas; si por ejemplo es de parquet en espiga o tiene mosaico hidr\u00e1ulico, las alfombras de pelo corto y lisas ser\u00e1n la apuesta ganadora, mientras que un suelo liso puede pedir una alfombra con alg\u00fan motivo original, lo que incluye flores, formas geom\u00e9tricas o un dibujo en zig zag. En todo caso, recuerda que, en el sal\u00f3n, las alfombras deben ser grandes. <\/span><b>Si vas a comer en ella, ya sea a diario o de manera ocasional, tanto la mesa como todas las sillas deben quedar dentro de la alfombra, incluso cuando los comensales se echan hacia atr\u00e1s para levantarse<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<figure id=\"attachment_16907\" aria-describedby=\"caption-attachment-16907\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/textil\/alfombras?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16907 size-full\" title=\"Alfombra PANPAN\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-5.jpg\" alt=\"tendencias salon \" width=\"600\" height=\"900\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-5.jpg 400w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-5-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-5-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-5-160x240.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-16907\" class=\"wp-caption-text\">Alfombra PANPAN<\/figcaption><\/figure>\n<h2><strong>5. El estilo industrial que vino para quedarse<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Tu sal\u00f3n puede inspirarse en los lofts neoyorquinos en los que naci\u00f3 esta tendencia, asentada en los \u00faltimos a\u00f1os y con mucho recorrido a\u00fan en el tiempo. Pi\u00e9rdele el miedo a las paredes de ladrillo, las vigas de madera, los pilares de hormig\u00f3n, los muebles vintage en los que predomina el hierro, los tablones de madera de roble en el suelo, los flexos de lat\u00f3n o las ventanas arqueadas.<\/span><\/p>\n<p><b>Aprovecha en tu favor la vigencia de una de esas tendencias para el sal\u00f3n que mejor combina la decoraci\u00f3n con el aprovechamiento del espacio. <\/b><span style=\"font-weight: 400;\">Conviene recordar que en este estilo la amplitud, as\u00ed como la entrada de luz natural, es imprescindible.<\/span><\/p>\n<figure id=\"attachment_16909\" aria-describedby=\"caption-attachment-16909\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-salon?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16909 size-full\" title=\"Sal\u00f3n INDUSTRY\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-6.jpg\" alt=\"tendencias salon\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-6.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-6-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-6-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-6-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption id=\"caption-attachment-16909\" class=\"wp-caption-text\">Sal\u00f3n INDUSTRY<\/figcaption><\/figure>\n<h2><strong>6. Elige colores neutros para las cortinas<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Se acabaron los tiempos en los que las cortinas del sal\u00f3n eran protagonistas. Ahora son ellas las que dejan el papel principal a los muebles y a las alfombras. <\/span><b>Los colores predominantes en las nuevas tendencias para el sal\u00f3n son los blancos, los grises y los beiges. <\/b><span style=\"font-weight: 400;\">Es una ventaja, ya que combinan bien con estilos muy diferentes y aportan mucha luz, o al menos no la restan si tu sal\u00f3n no tiene demasiada.&nbsp;<\/span><\/p>\n<p><b>Escoge modelos de cortinas que se adapten al tipo de ventanas con las que cuentes, ya sean de guillotina, correderas o abatibles, y comprueba que las que adquieres son resistentes<\/b><span style=\"font-weight: 400;\">. Con este tipo de cortinas monocrom\u00e1ticas podr\u00e1s no solo definir el estilo de toda la estancia, sino tambi\u00e9n regular la iluminaci\u00f3n y la temperatura, adem\u00e1s de reducir el ruido exterior.<\/span><\/p>\n<figure id=\"attachment_16911\" aria-describedby=\"caption-attachment-16911\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/textil\/cortinas-y-estores?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16911 size-full\" title=\"Sal\u00f3n VERONA con decoraci\u00f3n Exotic Chic\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-7.jpg\" alt=\"tendencias salon \" width=\"600\" height=\"900\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-7.jpg 600w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-7-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-7-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-7-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon-7-160x240.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-16911\" class=\"wp-caption-text\">Sal\u00f3n VERONA con decoraci\u00f3n Exotic Chic<\/figcaption><\/figure>\n<h2><strong>\u00a1Haz tuyos estos consejos y descubre tu tendencia preferida!<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">El sal\u00f3n es ese lugar de la casa en el que todo el mundo piensa cuando est\u00e1 fuera de ella. Porque no solo en \u00e9l hacemos vida familiar, sino que es un espacio en el que recibir a invitados, ver una pel\u00edcula, disputar un juego de mesa o, simplemente, encontrar tiempo para la lectura. \u00a1Haz tuyos estos consejos y descubre las <strong>tendencias para sal\u00f3n<\/strong> que mejor se adapten a lo que est\u00e1s buscando!<\/span><\/p>\n<p style=\"text-align: center;\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es uno de los lugares de la casa donde m\u00e1s tiempo se pasa al d\u00eda,<\/p>\n","protected":false},"author":10,"featured_media":16884,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1400,1789],"tags":[1555],"class_list":["post-16883","post","type-post","status-publish","format-standard","has-post-thumbnail","placeholder-for-hentry","category-decoracion-estancias","category-decoracion-salon","tag-salon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tendencias para el sal\u00f3n: 6 claves para este 2020<\/title>\n<meta name=\"description\" content=\"\u00a1Es el centro de toda vivienda, por funcionalidad y por estilo! \u00daltimas tendencias para tu sal\u00f3n este 2020, \u00a1con\u00f3celas todas!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tendencias para el sal\u00f3n: 6 claves para este 2020\" \/>\n<meta property=\"og:description\" content=\"\u00a1Es el centro de toda vivienda, por funcionalidad y por estilo! \u00daltimas tendencias para tu sal\u00f3n este 2020, \u00a1con\u00f3celas todas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/\" \/>\n<meta property=\"og:site_name\" content=\"Conforama\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-17T18:17:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-24T10:55:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Conforama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conforama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/\"},\"author\":{\"name\":\"Conforama\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\"},\"headline\":\"Tendencias para el sal\u00f3n: 6 claves para este 2020\",\"datePublished\":\"2019-10-17T18:17:53+00:00\",\"dateModified\":\"2022-10-24T10:55:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/\"},\"wordCount\":1279,\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg\",\"keywords\":[\"sal\u00f3n\"],\"articleSection\":[\"Decoraci\u00f3n\",\"Decoraci\u00f3n de sal\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/\",\"url\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/\",\"name\":\"Tendencias para el sal\u00f3n: 6 claves para este 2020\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg\",\"datePublished\":\"2019-10-17T18:17:53+00:00\",\"dateModified\":\"2022-10-24T10:55:14+00:00\",\"description\":\"\u00a1Es el centro de toda vivienda, por funcionalidad y por estilo! \u00daltimas tendencias para tu sal\u00f3n este 2020, \u00a1con\u00f3celas todas!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage\",\"url\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg\",\"contentUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg\",\"width\":762,\"height\":250,\"caption\":\"tendencias salon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.conforama.live\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decoraci\u00f3n\",\"item\":\"https:\/\/www.conforama.live\/blog\/decoracion-estancias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tendencias para el sal\u00f3n: 6 claves para este 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"name\":\"Blog Conforama\",\"description\":\"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos\",\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conforama.live\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\",\"name\":\"Conforama\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"contentUrl\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"width\":265,\"height\":72,\"caption\":\"Conforama\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\",\"name\":\"Conforama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"caption\":\"Conforama\"},\"url\":\"https:\/\/www.conforama.live\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tendencias para el sal\u00f3n: 6 claves para este 2020","description":"\u00a1Es el centro de toda vivienda, por funcionalidad y por estilo! \u00daltimas tendencias para tu sal\u00f3n este 2020, \u00a1con\u00f3celas todas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/","og_locale":"es_ES","og_type":"article","og_title":"Tendencias para el sal\u00f3n: 6 claves para este 2020","og_description":"\u00a1Es el centro de toda vivienda, por funcionalidad y por estilo! \u00daltimas tendencias para tu sal\u00f3n este 2020, \u00a1con\u00f3celas todas!","og_url":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/","og_site_name":"Conforama","article_published_time":"2019-10-17T18:17:53+00:00","article_modified_time":"2022-10-24T10:55:14+00:00","og_image":[{"width":762,"height":250,"url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg","type":"image\/jpeg"}],"author":"Conforama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Conforama","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#article","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/"},"author":{"name":"Conforama","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e"},"headline":"Tendencias para el sal\u00f3n: 6 claves para este 2020","datePublished":"2019-10-17T18:17:53+00:00","dateModified":"2022-10-24T10:55:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/"},"wordCount":1279,"publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg","keywords":["sal\u00f3n"],"articleSection":["Decoraci\u00f3n","Decoraci\u00f3n de sal\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/","url":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/","name":"Tendencias para el sal\u00f3n: 6 claves para este 2020","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg","datePublished":"2019-10-17T18:17:53+00:00","dateModified":"2022-10-24T10:55:14+00:00","description":"\u00a1Es el centro de toda vivienda, por funcionalidad y por estilo! \u00daltimas tendencias para tu sal\u00f3n este 2020, \u00a1con\u00f3celas todas!","breadcrumb":{"@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#primaryimage","url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg","contentUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2019\/10\/tendencias-salon.jpg","width":762,"height":250,"caption":"tendencias salon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conforama.live\/blog\/6-tendencias-para-el-salon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conforama.live\/blog\/"},{"@type":"ListItem","position":2,"name":"Decoraci\u00f3n","item":"https:\/\/www.conforama.live\/blog\/decoracion-estancias\/"},{"@type":"ListItem","position":3,"name":"Tendencias para el sal\u00f3n: 6 claves para este 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.conforama.live\/blog\/#website","url":"https:\/\/www.conforama.live\/blog\/","name":"Blog Conforama","description":"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos","publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conforama.live\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.conforama.live\/blog\/#organization","name":"Conforama","url":"https:\/\/www.conforama.live\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","contentUrl":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","width":265,"height":72,"caption":"Conforama"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e","name":"Conforama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","caption":"Conforama"},"url":"https:\/\/www.conforama.live\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/16883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/comments?post=16883"}],"version-history":[{"count":14,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/16883\/revisions"}],"predecessor-version":[{"id":35689,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/16883\/revisions\/35689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media\/16884"}],"wp:attachment":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media?parent=16883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/categories?post=16883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/tags?post=16883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}