{"id":26652,"date":"2021-04-19T08:00:47","date_gmt":"2021-04-19T06:00:47","guid":{"rendered":"https:\/\/www.conforama.live\/blog\/?p=26652"},"modified":"2022-10-24T15:42:56","modified_gmt":"2022-10-24T13:42:56","slug":"tipo-bombillas-claves-al-elegirlas","status":"publish","type":"post","link":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/","title":{"rendered":"Tipo de bombillas y las claves para no equivocarte al elegirlas"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Hay un <\/span><b>tipo de bombillas<\/b><span style=\"font-weight: 400;\"> ideal para ti. Y acertar con tu media naranja en iluminaci\u00f3n, \u00a1es realmente muy f\u00e1cil! Solo tienes que leer, antes de adquirir tu pr\u00f3xima bombilla, nuestra peque\u00f1a gu\u00eda con las recomendaciones a tener en cuenta. Enriquece tus habitaciones y aprovecha al m\u00e1ximo el potencial de tus l\u00e1mparas, poni\u00e9ndolas en pr\u00e1ctica. <\/span><\/p>\n<figure id=\"attachment_26655\" aria-describedby=\"caption-attachment-26655\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26655 size-full\" title=\"Iluminaci\u00f3n - Conforama\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas-de-bajo-consumo.jpg\" alt=\"tipo bombillas\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas-de-bajo-consumo.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas-de-bajo-consumo-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas-de-bajo-consumo-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas-de-bajo-consumo-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-26655\" class=\"wp-caption-text\">La luz no solo ilumina, tambi\u00e9n destaca objetos. La <a target=\"_blank\" href=\"https:\/\/www.conforama.live\/muebles\/almacenaje\/aparadores?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\" title=\"Aparadores y vitrinas\">vitrina<\/a> de 2 puertas de la colecci\u00f3n sal\u00f3n DIMARO, te permite incorporar iluminaci\u00f3n led. Organiza y decora con estilo.<\/figcaption><\/figure>\n<h2><strong>Tipo de bombillas seg\u00fan su consumo<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">La luz natural o artificial acompa\u00f1a la mayor\u00eda de nuestras actividades diarias. Y el tipo de bombillas que usamos, influye en el gasto dom\u00e9stico.<\/span><\/p>\n<p style=\"text-align: center;\"><\/p>\n<p><span style=\"font-weight: 400;\">Por ello, desde hace algunos a\u00f1os las bombillas incandescentes y hal\u00f3genas se han dejado de fabricar, aunque siguen a la venta mientras haya existencias.<\/span><\/p>\n<figure id=\"attachment_26657\" aria-describedby=\"caption-attachment-26657\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26657 size-full\" title=\"Iluminaci\u00f3n - Conforama\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/clases-de-bombillas.jpg\" alt=\"tipo bombillas\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/clases-de-bombillas.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/clases-de-bombillas-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/clases-de-bombillas-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/clases-de-bombillas-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-26657\" class=\"wp-caption-text\">\u00bfTe gusta el estilo moderno? \u00bfY el industrial? Ll\u00e9valos al interior de tu casa con la <a target=\"_blank\" href=\"https:\/\/www.conforama.live\/decoracion\/iluminacion\/lamparas\/lamparas-de-techo?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\" title=\"L\u00e1mparas de techo\">l\u00e1mpara de techo<\/a> FRIDA.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">De mayor a menor consumo, puedes encontrar:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Bombillas incandescentes<\/b><span style=\"font-weight: 400;\">. Poca vida \u00fatil, <\/span><b>elevado consumo<\/b><span style=\"font-weight: 400;\"> el\u00e9ctrico. Solo usan el 5% de la energ\u00eda que gastan para iluminar.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Bombillas hal\u00f3genas<\/b><span style=\"font-weight: 400;\">. Consumen menos que las anteriores. Generan mucho calor.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Bombillas fluocompactas o bombillas de bajo consumo<\/b><span style=\"font-weight: 400;\">. Reducen el consumo hasta en un 80% con respecto a las convencionales bombillas incandescentes. Su duraci\u00f3n es muy superior (6.000-10.000 horas). Tardan en obtener la m\u00e1xima potencia. <\/span><b>Encender y apagar continuamente recorta su vida \u00fatil<\/b><span style=\"font-weight: 400;\">. No es aconsejable su uso en zonas de paso.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Bombillas LED<\/b> (Light Emitting Diode). Sus caracter\u00edsticas rebasan a las dem\u00e1s: tienen una <b>larga vida \u00fatil<\/b> (unas 50.000 horas), <b>encendido instant\u00e1neo<\/b>, toleran un gran n\u00famero de fases de encendido y apagado, no emiten pr\u00e1cticamente calor y son m\u00e1s sostenibles al poder ser recicladas y no contener mercurio.<\/li>\n<\/ul>\n<blockquote><p>El fabricante suele se\u00f1alar en cada dispositivo, mediante un adhesivo, o en las instrucciones, cu\u00e1l es la potencia m\u00e1xima permitida (vatios W). Rev\u00edsalo para adquirir el tipo de bombilla correcto.<\/p><\/blockquote>\n<figure id=\"attachment_26659\" aria-describedby=\"caption-attachment-26659\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26659 size-full\" title=\"Iluminaci\u00f3n - Conforama\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-led.jpg\" alt=\"tipo bombillas\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-led.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-led-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-led-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-led-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-26659\" class=\"wp-caption-text\">Un espacio de trabajo tambi\u00e9n puede ser original. Juega, por ejemplo, con un aplique de pared y un <a target=\"_blank\" href=\"https:\/\/www.conforama.live\/decoracion\/iluminacion\/lamparas\/flexos?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\" title=\"Flexos\">flexo<\/a>.<\/figcaption><\/figure>\n<h2><strong>5 consejos para elegir el tipo de bombillas que necesitas en tu casa<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Tarde o temprano llega ese momento en que toca cambiar las bombillas de la l\u00e1mpara de techo del sal\u00f3n, del foco del recibidor o de la l\u00e1mpara de sobremesa del dormitorio. \u00bfQu\u00e9 claves pueden ayudarte a acertar y elegir el tipo de bombillas adecuado?<\/span><\/p>\n<h3><strong>El casquillo<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Es<\/span> <span style=\"font-weight: 400;\">la<\/span><b> parte de la bombilla que se acopla a la luminaria<\/b><span style=\"font-weight: 400;\">. Los m\u00e1s comunes son:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para bombillas de rosca, el <\/span><b>E27 o rosca grande<\/b><span style=\"font-weight: 400;\"> o Edison, y el <\/span><b>E14 o rosca peque\u00f1a.<\/b><span style=\"font-weight: 400;\"> Por su forma de vela o gota, estos suelen usarse en l\u00e1mparas decorativas como las de ara\u00f1a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En focos empotrables, los conocidos como casquillos bayonetas, debido a sus salientes que sustituyen la rosca por dos protuberancias. El <\/span><b>GU10,<\/b><span style=\"font-weight: 400;\"> para focos empotrables con transformador y el <\/span><b>GU5.3<\/b><span style=\"font-weight: 400;\"> para focos empotrables sin transformador.<\/span><\/p>\n<blockquote><p>\u00bfQu\u00e9 significa E27 o GU10? La letra hace referencia al tipo de rosca, el n\u00famero al di\u00e1metro de la misma o a la distancia entre clavijas, en mil\u00edmetros.<\/p><\/blockquote>\n<figure id=\"attachment_26661\" aria-describedby=\"caption-attachment-26661\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26661 size-full\" title=\"Iluminaci\u00f3n - Conforama\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-e27.jpg\" alt=\"tipo bombillas\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-e27.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-e27-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-e27-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipos-de-bombillas-e27-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-26661\" class=\"wp-caption-text\">El dorado incrementa la sensaci\u00f3n de calidez y es tendencia. \u00a1A\u00f1\u00e1delo con la <a target=\"_blank\" href=\"https:\/\/www.conforama.live\/decoracion\/iluminacion\/lamparas\/lamparas-de-mesa?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\" title=\"L\u00e1mparas de mesa\">l\u00e1mpara de sobremesa<\/a> VISERBELLA y gana, tambi\u00e9n, elegancia!<\/figcaption><\/figure>\n<h3><strong>La forma del tipo de bombillas<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Hay diversos tipos de formas de bombillas: espiral, globo, redonda, vela\u2026<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Su apariencia influye en la est\u00e9tica de la l\u00e1mpara y, por tanto, sobre el ambiente. De ah\u00ed que el dise\u00f1o de la bombilla debe concordar con el de esta.<\/span><\/p>\n<figure id=\"attachment_26663\" aria-describedby=\"caption-attachment-26663\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26663 size-full\" title=\"Iluminaci\u00f3n - Conforama\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombilla-led-e27.jpg\" alt=\"tipo bombillas\" width=\"400\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombilla-led-e27.jpg 400w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombilla-led-e27-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombilla-led-e27-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombilla-led-e27-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombilla-led-e27-160x240.jpg 160w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-26663\" class=\"wp-caption-text\">Bombilla filamento led GLOBO. Este tipo de bombillas recuerdan mucho a las incandescentes, pero cuentan con tecnolog\u00eda m\u00e1s eficiente.<\/figcaption><\/figure>\n<h3><strong>El color de la luz<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">El tono de luz de una bombilla o grados Kelvin (K) es un indicativo de d\u00f3nde puedes utilizarla:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Blanco c\u00e1lido<\/b><span style=\"font-weight: 400;\">. Es una <\/span><b>luz m\u00e1s amarilla que crea ambientes acogedores<\/b><span style=\"font-weight: 400;\"> y agradables y, por ello, es ideal para <\/span><a href=\"https:\/\/www.conforama.live\/blog\/como-iluminar-un-salon-comedor-a-tus-necesidades\/\" title=\"C\u00f3mo iluminar un sal\u00f3n comedor para adaptarlo a tus necesidades\"><span style=\"font-weight: 400;\">iluminar salones<\/span><\/a><span style=\"font-weight: 400;\">, comedores, salas de estar o dormitorios (2.700-3.500\u00baK).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Blanco fr\u00edo<\/b><span style=\"font-weight: 400;\">. Es un <\/span><b>color m\u00e1s blanco<\/b><span style=\"font-weight: 400;\">, apto para lugares como oficinas, trasteros o garajes donde se precisa de mucha luz (5.000-6.500\u00baK).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Blanco puro<\/b>. Se trata de <b>un tono m\u00e1s neutro<\/b>, perfecto como <a href=\"https:\/\/www.conforama.live\/blog\/como-iluminar-una-cocina\/\" title=\"\u00bfC\u00f3mo iluminar una cocina para que siga las nuevas tendencias\">luz en cocinas<\/a> o ba\u00f1os (4.000-4.500\u00baK).<\/li>\n<\/ul>\n<figure id=\"attachment_26665\" aria-describedby=\"caption-attachment-26665\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26665 size-full\" title=\"Iluminaci\u00f3n - Conforama\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/luz-led.jpg\" alt=\"tipo bombillas\" width=\"400\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/luz-led.jpg 400w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/luz-led-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/luz-led-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/luz-led-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/luz-led-160x240.jpg 160w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-26665\" class=\"wp-caption-text\">Una l\u00e1mpara colgante puede introducir ese punto de atracci\u00f3n que quieres para tu casa. \u00bfQu\u00e9 te parece la l\u00e1mpara led FLEX?<\/figcaption><\/figure>\n<h3><strong>Los l\u00famenes<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Es la <\/span><b>cantidad de luz que produce<\/b><span style=\"font-weight: 400;\"> o la potencia lum\u00ednica, de una <\/span><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/decoracion\/iluminacion\/bombillas?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\" title=\"Bombillas\"><span style=\"font-weight: 400;\">bombilla<\/span><\/a><span style=\"font-weight: 400;\">: m\u00e1s l\u00famenes (lm) suponen m\u00e1s intensidad de luz.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al sustituir tus bombillas tradicionales por una con tecnolog\u00eda led, ten en cuenta que una bombilla led genera m\u00e1s potencia de luz con menos vatios.<\/span><\/p>\n<figure id=\"attachment_26667\" aria-describedby=\"caption-attachment-26667\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26667 size-full\" title=\"Iluminaci\u00f3n - Conforama\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombillas-decorativas.jpg\" alt=\"tipo bombillas\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombillas-decorativas.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombillas-decorativas-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombillas-decorativas-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/bombillas-decorativas-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-26667\" class=\"wp-caption-text\">La <a target=\"_blank\" href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-salon?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\" title=\"Muebles de sal\u00f3n\">combinaci\u00f3n de sal\u00f3n<\/a> VERONA tambi\u00e9n dispone de la opci\u00f3n de introducir luces led en su vitrina de 3 puertas. Convierte en protagonista a ese objeto que tanto te gusta.<\/figcaption><\/figure>\n<h3><strong>El \u00e1ngulo de apertura<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Al adquirir una bombilla tipo led, tienes que prestar atenci\u00f3n a este punto, pues te ayuda a saber d\u00f3nde puedes emplearla:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Menor \u00e1ngulo de apertura implica m\u00e1s luz puntual o focal<\/b><span style=\"font-weight: 400;\">. De ah\u00ed que sean propicias para, por ejemplo, dar luz a un cuadro de pared o a una vitrina y resaltar as\u00ed, un punto decorativo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>M\u00e1s \u00e1ngulo de apertura supone m\u00e1s luz general.<\/b><span style=\"font-weight: 400;\"> Esto las hace m\u00e1s adecuadas para la iluminaci\u00f3n de una habitaci\u00f3n.<\/span><\/li>\n<\/ul>\n<blockquote><p>Algunos tipos de bombillas led permiten regular la intensidad de la iluminaci\u00f3n. El indicativo \u00abdimmable\u00bb, te permitir\u00e1 identificar si cuentan con esta caracter\u00edstica.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Da luz a tu vida con l\u00e1mparas de techo, de sobremesa o apliques en tus techos, paredes o muebles. <\/span><b>Ilumina todas tus actividades<\/b><span style=\"font-weight: 400;\"> y decora al mismo tiempo tu casa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;  &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:637,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:[null,2,12040119]},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:[null,2,12040119]},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:[null,2,12040119]},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:[null,2,12040119]},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;12&quot;:0}\">  <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay un tipo de bombillas ideal para ti. Y acertar con tu media naranja en<\/p>\n","protected":false},"author":10,"featured_media":26653,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1851,1850],"tags":[],"class_list":["post-26652","post","type-post","status-publish","format-standard","has-post-thumbnail","placeholder-for-hentry","category-consejos-ahorro","category-consejos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tipo de bombillas: 5 trucos sencillos para acertar con la tuya<\/title>\n<meta name=\"description\" content=\"Existe un tipo de bombilla id\u00f3nea para cada una de tus l\u00e1mparas. \u00bfSabes c\u00faal es? Descubre en qu\u00e9 puntos tienes que fijarte para no fallar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipo de bombillas: 5 trucos sencillos para acertar con la tuya\" \/>\n<meta property=\"og:description\" content=\"Existe un tipo de bombilla id\u00f3nea para cada una de tus l\u00e1mparas. \u00bfSabes c\u00faal es? Descubre en qu\u00e9 puntos tienes que fijarte para no fallar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/\" \/>\n<meta property=\"og:site_name\" content=\"Conforama\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T06:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-24T13:42:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Conforama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conforama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/\"},\"author\":{\"name\":\"Conforama\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\"},\"headline\":\"Tipo de bombillas y las claves para no equivocarte al elegirlas\",\"datePublished\":\"2021-04-19T06:00:47+00:00\",\"dateModified\":\"2022-10-24T13:42:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/\"},\"wordCount\":1071,\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg\",\"articleSection\":[\"Ahorro\",\"Consejos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/\",\"url\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/\",\"name\":\"Tipo de bombillas: 5 trucos sencillos para acertar con la tuya\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg\",\"datePublished\":\"2021-04-19T06:00:47+00:00\",\"dateModified\":\"2022-10-24T13:42:56+00:00\",\"description\":\"Existe un tipo de bombilla id\u00f3nea para cada una de tus l\u00e1mparas. \u00bfSabes c\u00faal es? Descubre en qu\u00e9 puntos tienes que fijarte para no fallar.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage\",\"url\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg\",\"contentUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg\",\"width\":762,\"height\":250,\"caption\":\"tipo bombillas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.conforama.live\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejos\",\"item\":\"https:\/\/www.conforama.live\/blog\/consejos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tipo de bombillas y las claves para no equivocarte al elegirlas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"name\":\"Blog Conforama\",\"description\":\"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos\",\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conforama.live\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\",\"name\":\"Conforama\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"contentUrl\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"width\":265,\"height\":72,\"caption\":\"Conforama\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\",\"name\":\"Conforama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"caption\":\"Conforama\"},\"url\":\"https:\/\/www.conforama.live\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipo de bombillas: 5 trucos sencillos para acertar con la tuya","description":"Existe un tipo de bombilla id\u00f3nea para cada una de tus l\u00e1mparas. \u00bfSabes c\u00faal es? Descubre en qu\u00e9 puntos tienes que fijarte para no fallar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/","og_locale":"es_ES","og_type":"article","og_title":"Tipo de bombillas: 5 trucos sencillos para acertar con la tuya","og_description":"Existe un tipo de bombilla id\u00f3nea para cada una de tus l\u00e1mparas. \u00bfSabes c\u00faal es? Descubre en qu\u00e9 puntos tienes que fijarte para no fallar.","og_url":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/","og_site_name":"Conforama","article_published_time":"2021-04-19T06:00:47+00:00","article_modified_time":"2022-10-24T13:42:56+00:00","og_image":[{"width":762,"height":250,"url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg","type":"image\/jpeg"}],"author":"Conforama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Conforama","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#article","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/"},"author":{"name":"Conforama","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e"},"headline":"Tipo de bombillas y las claves para no equivocarte al elegirlas","datePublished":"2021-04-19T06:00:47+00:00","dateModified":"2022-10-24T13:42:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/"},"wordCount":1071,"publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg","articleSection":["Ahorro","Consejos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/","url":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/","name":"Tipo de bombillas: 5 trucos sencillos para acertar con la tuya","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg","datePublished":"2021-04-19T06:00:47+00:00","dateModified":"2022-10-24T13:42:56+00:00","description":"Existe un tipo de bombilla id\u00f3nea para cada una de tus l\u00e1mparas. \u00bfSabes c\u00faal es? Descubre en qu\u00e9 puntos tienes que fijarte para no fallar.","breadcrumb":{"@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#primaryimage","url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg","contentUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2021\/03\/tipo-bombillas.jpg","width":762,"height":250,"caption":"tipo bombillas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conforama.live\/blog\/tipo-bombillas-claves-al-elegirlas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conforama.live\/blog\/"},{"@type":"ListItem","position":2,"name":"Consejos","item":"https:\/\/www.conforama.live\/blog\/consejos\/"},{"@type":"ListItem","position":3,"name":"Tipo de bombillas y las claves para no equivocarte al elegirlas"}]},{"@type":"WebSite","@id":"https:\/\/www.conforama.live\/blog\/#website","url":"https:\/\/www.conforama.live\/blog\/","name":"Blog Conforama","description":"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos","publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conforama.live\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.conforama.live\/blog\/#organization","name":"Conforama","url":"https:\/\/www.conforama.live\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","contentUrl":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","width":265,"height":72,"caption":"Conforama"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e","name":"Conforama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","caption":"Conforama"},"url":"https:\/\/www.conforama.live\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/26652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/comments?post=26652"}],"version-history":[{"count":5,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/26652\/revisions"}],"predecessor-version":[{"id":35721,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/26652\/revisions\/35721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media\/26653"}],"wp:attachment":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media?parent=26652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/categories?post=26652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/tags?post=26652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}