{"id":34196,"date":"2022-06-17T09:00:44","date_gmt":"2022-06-17T07:00:44","guid":{"rendered":"https:\/\/www.conforama.live\/blog\/?p=34196"},"modified":"2022-05-31T15:10:41","modified_gmt":"2022-05-31T13:10:41","slug":"como-desmontar-lavadora","status":"publish","type":"post","link":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/","title":{"rendered":"C\u00f3mo desmontar f\u00e1cilmente el tambor de la lavadora"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34198 size-full\" title=\"Desmonta una lavadora paso a paso\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-facilmente-sacar-tambor.jpg\" alt=\"desmontar lavadora\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-facilmente-sacar-tambor.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-facilmente-sacar-tambor-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-facilmente-sacar-tambor-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-facilmente-sacar-tambor-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Una de las tareas m\u00e1s complejas en el bricolaje, probablemente por falta de instrucciones y de informaci\u00f3n, es el momento de <\/span><a href=\"https:\/\/www.conforama.live\/blog\/desmontar-un-canape\/\"><span style=\"font-weight: 400;\">desmontar cualquier mueble<\/span><\/a><span style=\"font-weight: 400;\"> o electrodom\u00e9stico. Desde Conforama queremos ayudarte en esta tarea y en el art\u00edculo de hoy hemos querido explicarte <\/span><b>c\u00f3mo desmontar el tambor de tu lavadora antigua<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:637,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:12040119}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;12&quot;:0}\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\">El reciclaje es una de las principales causas que nos llevan a desmembrar esos elementos de casa que ya no necesitamos, pero en los que siempre encontramos alguna pieza reutilizable. El tambor de <\/span><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/electrodomesticos\/lavadoras?utm_source=Blog&amp;utm_medium=lavadoras&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><span style=\"font-weight: 400;\">la lavadora<\/span><\/a><span style=\"font-weight: 400;\"> es un buen ejemplo de ello, por lo que, adem\u00e1s del desarmado, vamos a explicarte tambi\u00e9n algunos de <\/span><b>los motivos m\u00e1s habituales por los que aparecen problemas de este tipo en las lavadoras<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><strong>Materiales necesarios para desmontar el tambor de la lavadora<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de algo de habilidad y paciencia por tu parte, hay <\/span><b>determinadas herramientas que no pueden faltar cuando se trata de desmontar una lavadora para extraer su tambor<\/b><span style=\"font-weight: 400;\">. Necesitar\u00e1s cortar cables, as\u00ed que cuenta con unos alicates y tambi\u00e9n cualquier pieza alargada de metal que te permita hacer palanca.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, tambi\u00e9n <\/span><b>te vendr\u00e1 bien un destornillador<\/b><span style=\"font-weight: 400;\"> -a poder ser de bater\u00eda recargable- y llaves inglesas, en cuyo caso siempre es recomendable contar con una ajustable para asegurarte de que las medidas no supondr\u00e1n un problema para el proceso.<\/span><\/p>\n<h2><strong>Paso a paso para desmontar la lavadora: reutiliza el antiguo tambor<\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34199 size-full\" title=\"Desmontar la lavadora para extraer el tambor\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/extrae-tambor-desmontando-lavadora.jpg\" alt=\"desmontar lavadora\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/extrae-tambor-desmontando-lavadora.jpg 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/extrae-tambor-desmontando-lavadora-300x180.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/extrae-tambor-desmontando-lavadora-768x461.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/extrae-tambor-desmontando-lavadora-320x192.jpg 320w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Es importante tener en cuenta que <\/span><b>desmontar una lavadora no es una tarea sencilla y lleva su tiempo<\/b><span style=\"font-weight: 400;\">. Son varios los pasos que hay que llevar a cabo, aunque los hemos dividido en tres fases para que te resulte m\u00e1s sencillo el proceso: el desarmado <\/span><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/electrodomesticos?utm_source=Blog&amp;utm_medium=Electrodomesticos&amp;utm_campaign=Inbound+marketing\" rel=\"noopener\"><span style=\"font-weight: 400;\">exterior del electrodom\u00e9stico<\/span><\/a><span style=\"font-weight: 400;\">, la separaci\u00f3n de las piezas internas y, finalmente, la extracci\u00f3n del tambor.<\/span><\/p>\n<h3><strong>Desmonta el exterior de la lavadora<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">El primer paso que debes llevar a cabo es <\/span><b>el despiece de los elementos externos de tu lavadora<\/b><span style=\"font-weight: 400;\">. Empieza buscando los tornillos que ensamblan la tapadera de la lavadora -habitualmente se ubican en la parte trasera- y ret\u00edrala. A continuaci\u00f3n deber\u00e1s hacer lo mismo con el panel de mandos, cuyos tornillos podr\u00e1s encontrar f\u00e1cilmente al levantar la tapa.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34200 size-full\" title=\"Desarme exterior de la lavadora\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-parte-exterior.jpg\" alt=\"desmontar lavadora\" width=\"600\" height=\"900\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-parte-exterior.jpg 600w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-parte-exterior-200x300.jpg 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-parte-exterior-512x768.jpg 512w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-parte-exterior-384x576.jpg 384w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/desmontar-lavadora-parte-exterior-160x240.jpg 160w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Cuando tires del panel, ver\u00e1s varios cables que se conectan a \u00e9l, trata de desconectarlos y, si no es posible, c\u00f3rtalos. Por \u00faltimo, necesitas buscar los tornillos que unen <\/span><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/electrodomesticos\/lavadoras\/lavadoras-de-carga-frontal\" rel=\"noopener\"><span style=\"font-weight: 400;\">el frontal de la lavadora<\/span><\/a><span style=\"font-weight: 400;\"> con el resto de piezas, desatornillarlos y tirar de \u00e9l hacia fuera para separarlo. A partir de este momento, <\/span><b>vamos a enfrentarnos al interior del electrodom\u00e9stico<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h3><strong>Desmonta los mecanismos internos de la lavadora<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">La segunda fase del desarmado resulta ligeramente m\u00e1s compleja, pero nada que no se pueda resolver con las instrucciones adecuadas. Se trata de <\/span><b>ir retirando todos los elementos que entorpezcan la extracci\u00f3n del propio tambor<\/b><span style=\"font-weight: 400;\">, empezando por el contrapeso frontal. Empezamos con la misma operaci\u00f3n de siempre, desatornillando y tirando hacia afuera.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando termines con este paso, encontrar\u00e1s una barra horizontal que est\u00e1 unida al tambor mediante unos muelles, se utiliza para darle estabilidad y tambi\u00e9n se desenrosca. En cambio, para retirar el contrapeso superior deber\u00e1s recurrir a la llave inglesa para aflojar las tuercas que lo fijan. Finalmente, queda por separar el caj\u00f3n del detergente y <\/span><b>los cables restantes para poder sacar el tambor de la lavadora<\/b><span style=\"font-weight: 400;\">, para lo cual tambi\u00e9n necesitar\u00e1s la llave regulable.<\/span><\/p>\n<h3><strong>Desmonta el tambor de la lavadora<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34201 size-full\" title=\"Paso final al desmontar la lavadora: extraer el tambor\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-extraer-tambor-lavadora.jpg\" alt=\"desmontar lavadora\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-extraer-tambor-lavadora.jpg 900w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-extraer-tambor-lavadora-300x200.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-extraer-tambor-lavadora-768x512.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-extraer-tambor-lavadora-320x213.jpg 320w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><b>Una vez que el tambor de la lavadora est\u00e1 fuera, solamente hace falta desmontar las piezas que lo rodean<\/b><span style=\"font-weight: 400;\">. Es una tarea entretenida, ya que hablamos de la polea, el motor, el eje y la cobertura pl\u00e1stica del tambor. En los dos primeros casos se trata de desatornillar, mientras que para desunir el eje es necesario hacer palanca. Lo \u00fanico que te queda por hacer es limpiar el tambor con productos espec\u00edficos para acero inoxidable para eliminar la cal.<\/span><\/p>\n<h2><strong>\u00bfPor qu\u00e9 se ha estropeado el tambor de tu lavadora?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Existen diversos motivos que nos pueden llevar a tener que <\/span><b>desmontar una lavadora que presenta problemas en el tambor<\/b><span style=\"font-weight: 400;\">. En algunos casos la aver\u00eda tiene f\u00e1cil soluci\u00f3n, mientras que en otros es posible que sea m\u00e1s rentable <\/span><a target=\"_blank\" href=\"https:\/\/www.conforama.live\/electrodomesticos\/lavadoras\/lavadoras-secadoras?utm_source=Blog&amp;utm_medium=lavadoras+secadoras&amp;utm_campaign=Inbound+Marketing\" rel=\"noopener\"><span style=\"font-weight: 400;\">adquirir una nueva lavadora<\/span><\/a><span style=\"font-weight: 400;\"> que reparar la antigua.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre <\/span><b>las causas principales que propician este desperfecto<\/b><span style=\"font-weight: 400;\">, encontramos los posibles fallos en el motor o en el cuadro de mandos -los fallos m\u00e1s complejos-, un desgaste en las escobillas del motor, una rotura en la correa de distribuci\u00f3n o alguna obstrucci\u00f3n que impide el correcto vaciado de la lavadora.<\/span><\/p>\n<p style=\"text-align: center;\"><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:513,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0}\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las tareas m\u00e1s complejas en el bricolaje, probablemente por falta de instrucciones y<\/p>\n","protected":false},"author":10,"featured_media":34197,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1893],"tags":[1602,1557,1842],"class_list":["post-34196","post","type-post","status-publish","format-standard","has-post-thumbnail","placeholder-for-hentry","category-averias","tag-cocina","tag-diy","tag-electrodomesticos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aprende a desmontar un tambor de lavadora f\u00e1cilmente<\/title>\n<meta name=\"description\" content=\"\u00bfLa lavadora no funciona y tienes que desmontarla para intentar un arreglo casero? Aprende a c\u00f3mo desmontar el tambor al detalle\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprende a desmontar un tambor de lavadora f\u00e1cilmente\" \/>\n<meta property=\"og:description\" content=\"\u00bfLa lavadora no funciona y tienes que desmontarla para intentar un arreglo casero? Aprende a c\u00f3mo desmontar el tambor al detalle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/\" \/>\n<meta property=\"og:site_name\" content=\"Conforama\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-17T07:00:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Conforama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conforama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/\"},\"author\":{\"name\":\"Conforama\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\"},\"headline\":\"C\u00f3mo desmontar f\u00e1cilmente el tambor de la lavadora\",\"datePublished\":\"2022-06-17T07:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/\"},\"wordCount\":795,\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg\",\"keywords\":[\"Cocina\",\"DIY\",\"electrodom\u00e9sticos\"],\"articleSection\":[\"Aver\u00edas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/\",\"url\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/\",\"name\":\"Aprende a desmontar un tambor de lavadora f\u00e1cilmente\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg\",\"datePublished\":\"2022-06-17T07:00:44+00:00\",\"description\":\"\u00bfLa lavadora no funciona y tienes que desmontarla para intentar un arreglo casero? Aprende a c\u00f3mo desmontar el tambor al detalle\",\"breadcrumb\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage\",\"url\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg\",\"contentUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg\",\"width\":1200,\"height\":390,\"caption\":\"desmontar-lavadora\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.conforama.live\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aver\u00edas\",\"item\":\"https:\/\/www.conforama.live\/blog\/averias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo desmontar f\u00e1cilmente el tambor de la lavadora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"name\":\"Blog Conforama\",\"description\":\"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos\",\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conforama.live\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\",\"name\":\"Conforama\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"contentUrl\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"width\":265,\"height\":72,\"caption\":\"Conforama\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\",\"name\":\"Conforama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"caption\":\"Conforama\"},\"url\":\"https:\/\/www.conforama.live\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprende a desmontar un tambor de lavadora f\u00e1cilmente","description":"\u00bfLa lavadora no funciona y tienes que desmontarla para intentar un arreglo casero? Aprende a c\u00f3mo desmontar el tambor al detalle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/","og_locale":"es_ES","og_type":"article","og_title":"Aprende a desmontar un tambor de lavadora f\u00e1cilmente","og_description":"\u00bfLa lavadora no funciona y tienes que desmontarla para intentar un arreglo casero? Aprende a c\u00f3mo desmontar el tambor al detalle","og_url":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/","og_site_name":"Conforama","article_published_time":"2022-06-17T07:00:44+00:00","og_image":[{"width":1200,"height":390,"url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg","type":"image\/jpeg"}],"author":"Conforama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Conforama","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#article","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/"},"author":{"name":"Conforama","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e"},"headline":"C\u00f3mo desmontar f\u00e1cilmente el tambor de la lavadora","datePublished":"2022-06-17T07:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/"},"wordCount":795,"publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg","keywords":["Cocina","DIY","electrodom\u00e9sticos"],"articleSection":["Aver\u00edas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/","url":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/","name":"Aprende a desmontar un tambor de lavadora f\u00e1cilmente","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg","datePublished":"2022-06-17T07:00:44+00:00","description":"\u00bfLa lavadora no funciona y tienes que desmontarla para intentar un arreglo casero? Aprende a c\u00f3mo desmontar el tambor al detalle","breadcrumb":{"@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#primaryimage","url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg","contentUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/05\/como-cambiar-tambor-lavadora.jpg","width":1200,"height":390,"caption":"desmontar-lavadora"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conforama.live\/blog\/como-desmontar-lavadora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conforama.live\/blog\/"},{"@type":"ListItem","position":2,"name":"Aver\u00edas","item":"https:\/\/www.conforama.live\/blog\/averias\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo desmontar f\u00e1cilmente el tambor de la lavadora"}]},{"@type":"WebSite","@id":"https:\/\/www.conforama.live\/blog\/#website","url":"https:\/\/www.conforama.live\/blog\/","name":"Blog Conforama","description":"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos","publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conforama.live\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.conforama.live\/blog\/#organization","name":"Conforama","url":"https:\/\/www.conforama.live\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","contentUrl":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","width":265,"height":72,"caption":"Conforama"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e","name":"Conforama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","caption":"Conforama"},"url":"https:\/\/www.conforama.live\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/34196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/comments?post=34196"}],"version-history":[{"count":3,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/34196\/revisions"}],"predecessor-version":[{"id":34442,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/34196\/revisions\/34442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media\/34197"}],"wp:attachment":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media?parent=34196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/categories?post=34196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/tags?post=34196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}