{"id":35474,"date":"2022-08-29T10:16:22","date_gmt":"2022-08-29T08:16:22","guid":{"rendered":"https:\/\/www.conforama.live\/blog\/?p=35474"},"modified":"2022-10-24T13:24:21","modified_gmt":"2022-10-24T11:24:21","slug":"como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo","status":"publish","type":"post","link":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/","title":{"rendered":"\u00bfC\u00f3mo trabajar en casa? Recomendaciones b\u00e1sicas para el teletrabajo"},"content":{"rendered":"\n<p><strong>El teletrabajo o homeoffice se ha instalado en la mayor\u00eda de puestos de trabajo de oficina<\/strong>. Lo que en un principio fue una medida extraordinaria para frenar el avance del coronavirus, se ha convertido en algo habitual y normalizado. Esto es as\u00ed hasta el punto de que <strong>actualmente la cifra de personas teletrabajando es casi del doble que antes de iniciarse la pandemia<\/strong>.&nbsp;<\/p>\n\n\n\n\n\n\n\n<p><\/p>\n\n\n\n<p>Esto ha llevado a que muchas personas hayan tenido que adaptar un rinc\u00f3n de su casa y convertirlo<a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-oficina?utm_source=Blog&amp;utm_medium=muebles+oficina&amp;utm_campaign=Inbound+Marketing\"> <strong>en despacho o sala de trabajo<\/strong><\/a>. Tambi\u00e9n, a mejorar o acondicionar esta estancia si ya exist\u00eda. Sin embargo, si tu lugar de teletrabajo no cuenta con unas condiciones b\u00e1sicas de ergonom\u00eda y confort, trabajar desde casa puede pasar factura a tu salud. No te pierdas las<strong> recomendaciones de teletrabajo que te traemos para que tu trabajo a distancia sea eficaz y c\u00f3modo a partes iguales<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-oficina\/escritorios?utm_source=Blog&amp;utm_medium=mesa+oficina&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/adult-woman-telecommuting-in-home-office-1024x682.jpg\" alt=\"\" class=\"wp-image-35480\" width=\"780\" height=\"519\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/adult-woman-telecommuting-in-home-office-1024x682.jpg 1024w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/adult-woman-telecommuting-in-home-office-300x200.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/adult-woman-telecommuting-in-home-office-768x512.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/adult-woman-telecommuting-in-home-office.jpg 1280w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">La importancia de la ergonom\u00eda<\/h2>\n\n\n\n<p>Que tu despacho en casa sea <strong>ergon\u00f3mico <\/strong>significa que las herramientas que uses, desde la silla al escritorio pasando por el rat\u00f3n, <strong>presenten un dise\u00f1o que se adapte y coincida con las caracter\u00edsticas f\u00edsicas de tu cuerpo.<\/strong> De esta manera no estar\u00e1s forzando tu postura. Si te est\u00e1s preguntando \u201c\u00bfpor qu\u00e9 tengo dolor de espalda cuando teletrabajo?\u201d, es probable que tu lugar de trabajo no cumpla con la ergonom\u00eda suficiente.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escogiendo la silla, el elemento clave<\/h2>\n\n\n\n<p>En este punto, en el de la ergonom\u00eda, es especialmente importante la silla. En la silla vas a pasar muchas horas sentado, del mismo modo que lo har\u00edas en la oficina, por eso<strong> necesitas <a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-dormitorios-de-matrimonio?utm_source=Blog&amp;utm_medium=silla+oficina&amp;utm_campaign=Inbound+Marketing\">una silla de escritorio o silla gaming<\/a> que permita adaptarse a la perfecci\u00f3n a la forma de tu espalda<\/strong>. Adem\u00e1s, desde ella debes poder acceder c\u00f3modamente a cajones, teclado, rat\u00f3n&nbsp; o a cualquier parte del sobre de la mesa\u2026 As\u00ed que evita usar sillas de comedor o cocina.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-oficina\/escritorios?utm_source=Blog&amp;utm_medium=mesa+oficina&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"483\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/sillas-teletrabajo-1024x483.jpg\" alt=\"\" class=\"wp-image-35475\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/sillas-teletrabajo-1024x483.jpg 1024w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/sillas-teletrabajo-300x141.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/sillas-teletrabajo-768x362.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/sillas-teletrabajo-1536x724.jpg 1536w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/sillas-teletrabajo-2048x966.jpg 2048w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/sillas-teletrabajo.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Si es posible, <strong>prueba tu silla de escritorio antes de comprarla<\/strong> para asegurarte que es la ideal en cuanto a medidas y comodidad. Una vez la tengas en casa, ajusta todas sus partes hasta conseguir la tan importante postura ideal para el teletrabajo.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1l es la postura correcta para teletrabajar?<\/h2>\n\n\n\n<p>La respuesta breve: deber\u00eda ser la misma que en la oficina. \u00bfY c\u00f3mo saber si la postura adoptada en la oficina es buena? Ah\u00ed va la respuesta larga:<\/p>\n\n\n\n<p>Si\u00e9ntate en la silla y <strong>aseg\u00farate de que tu espalda descansa sobre el respaldo, lo m\u00e1s recta posible y sin encorvarse. Tus hombros deber\u00edan quedar hacia atr\u00e1s y el cuello y la cabeza deber\u00edan estar alineados con los hombros,<\/strong> quedando tu cabeza sobre el coj\u00edn del respaldo, en caso de tener uno. Tu <strong>mirada deber\u00eda quedar alineada con la pantalla del ordenador<\/strong>. Comprueba tambi\u00e9n que <strong>tus pies toquen el suelo con las plantas<\/strong>, y si no es as\u00ed, configura la altura de la silla. <strong>Tus rodillas deben de quedar flexionadas <\/strong>y deber\u00edas poder acceder a todo lo que necesites sin tener que estirar demasiado los brazos. \u00a1As\u00ed s\u00ed que se teletrabaja a gusto!&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-oficina\/escritorios?utm_source=Blog&amp;utm_medium=mesa+oficina&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/Instruction-for-correct-pose-during-office-work-1024x682.jpg\" alt=\"\" class=\"wp-image-35476\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/Instruction-for-correct-pose-during-office-work-1024x682.jpg 1024w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/Instruction-for-correct-pose-during-office-work-300x200.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/Instruction-for-correct-pose-during-office-work-768x512.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/Instruction-for-correct-pose-during-office-work.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">El escritorio: porque no basta con una simple mesa<\/h2>\n\n\n\n<p>Del mismo modo que ocurri\u00f3 con las sillas, la manera apresurada en que se instaur\u00f3 el teletrabajo en el 2020 llev\u00f3 a que muchas personas improvisaran su lugar de trabajo. Por esto, recurrieron a mesas de comedor o cocina para teletrabajar. Pero <strong>nuestras recomendaciones para el teletrabajo <a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-oficina\/escritorios?utm_source=Blog&amp;utm_medium=mesa+oficina&amp;utm_campaign=Inbound+Marketing\">pasan tambi\u00e9n por conseguir un escritorio de despacho<\/a>.&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-oficina\/escritorios?utm_source=Blog&amp;utm_medium=mesa+oficina&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"569\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1024x569.jpg\" alt=\"\" class=\"wp-image-35478\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1024x569.jpg 1024w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-300x167.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-768x427.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Un escritorio de despacho<strong> te ofrece la superf\u00edcie necesaria para colocar tu ordenador port\u00e1til o de sobremesa y m\u00faltiples pantallas<\/strong>. Podr\u00e1s utilizar el rat\u00f3n apoyando la mano y parte del brazo sin forzar la postura, y desplazarlo por el sobre de la mesa sin que choque con otros elementos. Adem\u00e1s, un escritorio en condiciones deber\u00eda contar con cajones, estantes y huecos para disponer de todo el material de oficina y tenerlo bien cerca.&nbsp;<\/p>\n\n\n\n<p>Por cierto, no podemos olvidar algo de gran importancia. <strong>Tanto el escritorio como la silla deber\u00edan permitirte tambi\u00e9n jugar a tus juegos favoritos con la m\u00e1xima comodidad<\/strong>. \u00a1Eso s\u00ed! Siempre tras la jornada de teletrabajo.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Otras recomendaciones para el teletrabajo que no puedes pasar por alto<\/h2>\n\n\n\n<p>En las oficinas, las mesas est\u00e1n ubicadas (o deber\u00edan estarlo) <strong>de manera que la luz llega a tu lugar de trabajo desde un lado<\/strong>. As\u00ed se evita que la luz te moleste rebotando en la pantalla, si viene desde atr\u00e1s, o que sea muy pobre si viene desde el frente.&nbsp;<\/p>\n\n\n\n<p>En casa, debes procurar conseguir lo mismo. As\u00ed que <strong>ubica tu escritorio de lado respecto a la ventana o la fuente de luz<\/strong>. Quiz\u00e1s para esto debas cambiar la ubicaci\u00f3n de los muebles de tu despacho, pero te aseguramos que vale la pena y tu vista lo agradecer\u00e1.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s<strong> <a href=\"https:\/\/www.conforama.live\/decoracion\/iluminacion\/lamparas?utm_source=Blog&amp;utm_medium=lampara&amp;utm_campaign=Inbound+Marketing\">no puede faltarte una l\u00e1mpara<\/a> <\/strong>que <strong>te garantice las condiciones \u00f3ptimas de iluminaci\u00f3n para cuando la luz natural no sea suficiente<\/strong>. Opta por una luz de sobremesa, por ejemplo un flexo, o una l\u00e1mpara de pie. Combinar dos l\u00e1mparas para obtener una iluminaci\u00f3n adecuada tampoco es una mala idea.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.conforama.live\/muebles\/muebles-de-oficina\/escritorios?utm_source=Blog&amp;utm_medium=mesa+oficina&amp;utm_campaign=Inbound+Marketing\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/bearded-engineer-sitting-at-his-desk-in-home-office-working-on-turbine-1024x576.jpg\" alt=\"\" class=\"wp-image-35479\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/bearded-engineer-sitting-at-his-desk-in-home-office-working-on-turbine-1024x576.jpg 1024w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/bearded-engineer-sitting-at-his-desk-in-home-office-working-on-turbine-300x169.jpg 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/bearded-engineer-sitting-at-his-desk-in-home-office-working-on-turbine-768x432.jpg 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/bearded-engineer-sitting-at-his-desk-in-home-office-working-on-turbine.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Por supuesto, <strong>recuerda descansar de vez en cuando, igual que lo har\u00edas en la oficina<\/strong>. Cada hora deber\u00edas levantarte de la silla y estirarte por lo menos durante cinco minutos. Caminar por el pasillo tambi\u00e9n puede ser una buena opci\u00f3n. \u00bfQu\u00e9 tal un viaje a la cocina a por unos frutos secos o algo de fruta? Todo esto sin olvidar una hidrataci\u00f3n adecuada y una ventilaci\u00f3n correcta del espacio antes y despu\u00e9s de la jornada.&nbsp;<\/p>\n\n\n\n<p>Estas son <strong>nuestras recomendaciones para un teletrabajo c\u00f3modo, eficaz y muy productivo<\/strong>. Ahora ya sabes c\u00f3mo crear un lugar de trabajo a tu medida y qu\u00e9 aspectos tener en cuenta para el mejor teletrabajo. \u00a1As\u00ed que manos a la obra!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El teletrabajo o homeoffice se ha instalado en la mayor\u00eda de puestos de trabajo de<\/p>\n","protected":false},"author":10,"featured_media":35481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1850,1896,1854],"tags":[],"class_list":["post-35474","post","type-post","status-publish","format-standard","has-post-thumbnail","placeholder-for-hentry","category-consejos","category-decoracion-de-oficinas","category-consejos-hogar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Recomendaciones y consejos para teletrabajar en condiciones<\/title>\n<meta name=\"description\" content=\"El teletrabajo ha venido para quedarse. Estas son las recomendaciones para tener la ergoconom\u00eda necesar\u00eda para teletrabajar sin contratiempos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recomendaciones y consejos para teletrabajar en condiciones\" \/>\n<meta property=\"og:description\" content=\"El teletrabajo ha venido para quedarse. Estas son las recomendaciones para tener la ergoconom\u00eda necesar\u00eda para teletrabajar sin contratiempos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"Conforama\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-29T08:16:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-24T11:24:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Conforama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conforama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/\"},\"author\":{\"name\":\"Conforama\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\"},\"headline\":\"\u00bfC\u00f3mo trabajar en casa? Recomendaciones b\u00e1sicas para el teletrabajo\",\"datePublished\":\"2022-08-29T08:16:22+00:00\",\"dateModified\":\"2022-10-24T11:24:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/\"},\"wordCount\":1037,\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg\",\"articleSection\":[\"Consejos\",\"Decoraci\u00f3n de oficina\",\"Hogar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/\",\"url\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/\",\"name\":\"Recomendaciones y consejos para teletrabajar en condiciones\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg\",\"datePublished\":\"2022-08-29T08:16:22+00:00\",\"dateModified\":\"2022-10-24T11:24:21+00:00\",\"description\":\"El teletrabajo ha venido para quedarse. Estas son las recomendaciones para tener la ergoconom\u00eda necesar\u00eda para teletrabajar sin contratiempos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage\",\"url\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg\",\"contentUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg\",\"width\":1280,\"height\":711,\"caption\":\"recomendaciones teletrabajo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.conforama.live\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejos\",\"item\":\"https:\/\/www.conforama.live\/blog\/consejos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfC\u00f3mo trabajar en casa? Recomendaciones b\u00e1sicas para el teletrabajo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"name\":\"Blog Conforama\",\"description\":\"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos\",\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conforama.live\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\",\"name\":\"Conforama\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"contentUrl\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"width\":265,\"height\":72,\"caption\":\"Conforama\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\",\"name\":\"Conforama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"caption\":\"Conforama\"},\"url\":\"https:\/\/www.conforama.live\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recomendaciones y consejos para teletrabajar en condiciones","description":"El teletrabajo ha venido para quedarse. Estas son las recomendaciones para tener la ergoconom\u00eda necesar\u00eda para teletrabajar sin contratiempos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/","og_locale":"es_ES","og_type":"article","og_title":"Recomendaciones y consejos para teletrabajar en condiciones","og_description":"El teletrabajo ha venido para quedarse. Estas son las recomendaciones para tener la ergoconom\u00eda necesar\u00eda para teletrabajar sin contratiempos","og_url":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/","og_site_name":"Conforama","article_published_time":"2022-08-29T08:16:22+00:00","article_modified_time":"2022-10-24T11:24:21+00:00","og_image":[{"width":1280,"height":711,"url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg","type":"image\/jpeg"}],"author":"Conforama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Conforama","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#article","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/"},"author":{"name":"Conforama","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e"},"headline":"\u00bfC\u00f3mo trabajar en casa? Recomendaciones b\u00e1sicas para el teletrabajo","datePublished":"2022-08-29T08:16:22+00:00","dateModified":"2022-10-24T11:24:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/"},"wordCount":1037,"publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg","articleSection":["Consejos","Decoraci\u00f3n de oficina","Hogar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/","url":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/","name":"Recomendaciones y consejos para teletrabajar en condiciones","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg","datePublished":"2022-08-29T08:16:22+00:00","dateModified":"2022-10-24T11:24:21+00:00","description":"El teletrabajo ha venido para quedarse. Estas son las recomendaciones para tener la ergoconom\u00eda necesar\u00eda para teletrabajar sin contratiempos","breadcrumb":{"@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#primaryimage","url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg","contentUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2022\/08\/388605_04_06_09_10_14_Verona_AMB1-1.jpg","width":1280,"height":711,"caption":"recomendaciones teletrabajo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conforama.live\/blog\/como-trabajar-en-casa-recomendaciones-basicas-para-el-teletrabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conforama.live\/blog\/"},{"@type":"ListItem","position":2,"name":"Consejos","item":"https:\/\/www.conforama.live\/blog\/consejos\/"},{"@type":"ListItem","position":3,"name":"\u00bfC\u00f3mo trabajar en casa? Recomendaciones b\u00e1sicas para el teletrabajo"}]},{"@type":"WebSite","@id":"https:\/\/www.conforama.live\/blog\/#website","url":"https:\/\/www.conforama.live\/blog\/","name":"Blog Conforama","description":"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos","publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conforama.live\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.conforama.live\/blog\/#organization","name":"Conforama","url":"https:\/\/www.conforama.live\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","contentUrl":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","width":265,"height":72,"caption":"Conforama"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e","name":"Conforama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","caption":"Conforama"},"url":"https:\/\/www.conforama.live\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/35474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/comments?post=35474"}],"version-history":[{"count":6,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/35474\/revisions"}],"predecessor-version":[{"id":35707,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/35474\/revisions\/35707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media\/35481"}],"wp:attachment":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media?parent=35474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/categories?post=35474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/tags?post=35474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}