{"id":8391,"date":"2018-02-20T19:18:52","date_gmt":"2018-02-20T18:18:52","guid":{"rendered":"https:\/\/www.conforama.live\/blog\/?p=8391\/"},"modified":"2022-10-26T11:06:37","modified_gmt":"2022-10-26T09:06:37","slug":"llegan-los-dias-de-la-decoracion","status":"publish","type":"post","link":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/","title":{"rendered":"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!"},"content":{"rendered":"<p>\u00bfQu\u00e9 ser\u00eda de una casa si no fuera por la decoraci\u00f3n? Seguramente, poco m\u00e1s que habitaciones vac\u00edas&nbsp; en las que simplemente \u201chabitar\u201d. \u00a1Por eso en Conforama nos gusta tanto la <a href=\"https:\/\/www.conforama.live\/decoracion?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" title=\"Elementos de decoraci\u00f3n en Conforama\"><b>decoraci\u00f3n<\/b><\/a>!&nbsp;Porque nos permite crear espacios en los que no solo \u201chabitar\u201d, sino en los que VIVIR. Vivir sintiendo cada rinconcito como un lugar \u00fanico.<\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"D\u00edas de la Decoraci\u00f3n de Conforama aligncenter wp-image-8395 size-full\" title=\"D\u00edas de la Decoraci\u00f3n de Conforama\" src=\"\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog.png\" alt=\"D\u00edas de la Decoraci\u00f3n de Conforama\" width=\"1000\" height=\"600\" srcset=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog.png 1000w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog-300x180.png 300w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog-768x461.png 768w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog-200x120.png 200w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog-400x240.png 400w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog-600x360.png 600w, https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/1000x600-blog-800x480.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>La decoraci\u00f3n nos permite imprimir nuestra personalidad en cada estancia de nuestra casa, y llenarla de un encanto especial.<\/strong> Son esos peque\u00f1os detalles por los que al final acabas recordando una casa y no otra.<\/span><\/p>\n<h2 style=\"text-align: left;\">Vive la decoraci\u00f3n<\/h2>\n<p><span style=\"font-weight: 400;\">Y como queremos que te sumes y vivas esta pasi\u00f3n con nosotros, <strong>\u00a1arrancamos en Conforama los D\u00edas de la Decoraci\u00f3n!<\/strong> Durante esta semana y hasta el pr\u00f3ximo domingo 25, no te pierdas los concursos y sorpresas que tenemos para ti en nuestra p\u00e1gina de <\/span><a href=\"https:\/\/www.facebook.com\/ConforamaEspana\" title=\"Facebook oficial conforama.livepa\u00f1a\"><b>Facebook<\/b><\/a><span style=\"font-weight: 400;\"> y nuestra cuenta de&nbsp;<\/span><a href=\"https:\/\/www.instagram.com\/conforama.live\/\" title=\"Instagram Oficial conforama.livepa\u00f1a\"><b>Instagram<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esta ocasi\u00f3n, queremos reivindicar la importancia de los <\/span><a href=\"https:\/\/www.conforama.live\/textil\/ropa-de-cama?utm_source=Blog&amp;utm_medium=Generica&amp;utm_campaign=Inbound+Marketing\" title=\"Textiles cama en Conforama\"><b>textiles de cama<\/b><\/a><span style=\"font-weight: 400;\">, sin duda <strong>art\u00edculos genial\u00edsimos e ideales para aportar un aire tan especial a tu dormitorio<\/strong> como para no querer moverse de la cama los domingos (ni ning\u00fan otro d\u00eda); juegos de s\u00e1banas, cojines, n\u00f3rdicos\u2026<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por ejemplo, dec\u00e1ntate por unas preciosas s\u00e1banas con flamencos para la cama, y comb\u00ednalas con unos cactus decorativos en tu mesita de noche\u2026 \u00bfqui\u00e9n puede resistirse a una propuesta as\u00ed de colorida y genuinamente divertida para el dormitorio?<strong> \u00a1Ese es el poder de los textiles!<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">En definitiva, nos declaramos los mayores fans de la decoraci\u00f3n, y queremos que t\u00fa tambi\u00e9n lo seas. \u00a1As\u00ed que <strong>s\u00edguenos y no te pierdas los D\u00edas de la Decoraci\u00f3n de Conforama! &nbsp;<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 ser\u00eda de una casa si no fuera por la decoraci\u00f3n? Seguramente, poco m\u00e1s que<\/p>\n","protected":false},"author":10,"featured_media":8394,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1850,1400,1789,1854],"tags":[],"class_list":["post-8391","post","type-post","status-publish","format-standard","has-post-thumbnail","placeholder-for-hentry","category-consejos","category-decoracion-estancias","category-decoracion-salon","category-consejos-hogar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!<\/title>\n<meta name=\"description\" content=\"\u00a1Arrancamos en Conforama los D\u00edas de la Decoraci\u00f3n! S\u00edguenos y no te pierdas todas las sorpresas que tenemos preparadas para ti hasta el 25 de febrero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!\" \/>\n<meta property=\"og:description\" content=\"\u00a1Arrancamos en Conforama los D\u00edas de la Decoraci\u00f3n! S\u00edguenos y no te pierdas todas las sorpresas que tenemos preparadas para ti hasta el 25 de febrero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/\" \/>\n<meta property=\"og:site_name\" content=\"Conforama\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-20T18:18:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T09:06:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Conforama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conforama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/\"},\"author\":{\"name\":\"Conforama\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\"},\"headline\":\"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!\",\"datePublished\":\"2018-02-20T18:18:52+00:00\",\"dateModified\":\"2022-10-26T09:06:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/\"},\"wordCount\":307,\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png\",\"articleSection\":[\"Consejos\",\"Decoraci\u00f3n\",\"Decoraci\u00f3n de sal\u00f3n\",\"Hogar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/\",\"url\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/\",\"name\":\"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!\",\"isPartOf\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png\",\"datePublished\":\"2018-02-20T18:18:52+00:00\",\"dateModified\":\"2022-10-26T09:06:37+00:00\",\"description\":\"\u00a1Arrancamos en Conforama los D\u00edas de la Decoraci\u00f3n! S\u00edguenos y no te pierdas todas las sorpresas que tenemos preparadas para ti hasta el 25 de febrero.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage\",\"url\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png\",\"contentUrl\":\"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png\",\"width\":762,\"height\":250,\"caption\":\"blogdecoracion, tendencias, inspiracion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.conforama.live\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decoraci\u00f3n\",\"item\":\"https:\/\/www.conforama.live\/blog\/decoracion-estancias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#website\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"name\":\"Blog Conforama\",\"description\":\"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos\",\"publisher\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.conforama.live\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#organization\",\"name\":\"Conforama\",\"url\":\"https:\/\/www.conforama.live\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"contentUrl\":\"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png\",\"width\":265,\"height\":72,\"caption\":\"Conforama\"},\"image\":{\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e\",\"name\":\"Conforama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g\",\"caption\":\"Conforama\"},\"url\":\"https:\/\/www.conforama.live\/blog\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!","description":"\u00a1Arrancamos en Conforama los D\u00edas de la Decoraci\u00f3n! S\u00edguenos y no te pierdas todas las sorpresas que tenemos preparadas para ti hasta el 25 de febrero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!","og_description":"\u00a1Arrancamos en Conforama los D\u00edas de la Decoraci\u00f3n! S\u00edguenos y no te pierdas todas las sorpresas que tenemos preparadas para ti hasta el 25 de febrero.","og_url":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/","og_site_name":"Conforama","article_published_time":"2018-02-20T18:18:52+00:00","article_modified_time":"2022-10-26T09:06:37+00:00","og_image":[{"width":762,"height":250,"url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png","type":"image\/png"}],"author":"Conforama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Conforama","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#article","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/"},"author":{"name":"Conforama","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e"},"headline":"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!","datePublished":"2018-02-20T18:18:52+00:00","dateModified":"2022-10-26T09:06:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/"},"wordCount":307,"publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png","articleSection":["Consejos","Decoraci\u00f3n","Decoraci\u00f3n de sal\u00f3n","Hogar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/","url":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/","name":"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!","isPartOf":{"@id":"https:\/\/www.conforama.live\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png","datePublished":"2018-02-20T18:18:52+00:00","dateModified":"2022-10-26T09:06:37+00:00","description":"\u00a1Arrancamos en Conforama los D\u00edas de la Decoraci\u00f3n! S\u00edguenos y no te pierdas todas las sorpresas que tenemos preparadas para ti hasta el 25 de febrero.","breadcrumb":{"@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#primaryimage","url":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png","contentUrl":"https:\/\/www.conforama.live\/blog\/wp-content\/uploads\/2018\/02\/762x250-semana3-destacada.png","width":762,"height":250,"caption":"blogdecoracion, tendencias, inspiracion"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conforama.live\/blog\/llegan-los-dias-de-la-decoracion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conforama.live\/blog\/"},{"@type":"ListItem","position":2,"name":"Decoraci\u00f3n","item":"https:\/\/www.conforama.live\/blog\/decoracion-estancias\/"},{"@type":"ListItem","position":3,"name":"\u00a1Llegan los D\u00edas de la Decoraci\u00f3n a Conforama!"}]},{"@type":"WebSite","@id":"https:\/\/www.conforama.live\/blog\/#website","url":"https:\/\/www.conforama.live\/blog\/","name":"Blog Conforama","description":"Sof\u00e1s, colchones, muebles, decoraci\u00f3n y electrodom\u00e9sticos","publisher":{"@id":"https:\/\/www.conforama.live\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conforama.live\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.conforama.live\/blog\/#organization","name":"Conforama","url":"https:\/\/www.conforama.live\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","contentUrl":"https:\/\/www.conforama.live\/wp-content\/uploads\/2017\/10\/logo_es.png","width":265,"height":72,"caption":"Conforama"},"image":{"@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/62cafc5994386172033818d00473795e","name":"Conforama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conforama.live\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c82829c4e503bed5b2ab32b7dabd93244e6d254394dd790108c1dfbf56cc5e6?s=96&d=mm&r=g","caption":"Conforama"},"url":"https:\/\/www.conforama.live\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/8391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/comments?post=8391"}],"version-history":[{"count":13,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/8391\/revisions"}],"predecessor-version":[{"id":35821,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/posts\/8391\/revisions\/35821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media\/8394"}],"wp:attachment":[{"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/media?parent=8391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/categories?post=8391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conforama.live\/blog\/wp-json\/wp\/v2\/tags?post=8391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}